{"id":8101,"date":"2025-12-05T10:05:46","date_gmt":"2025-12-05T13:05:46","guid":{"rendered":"https:\/\/novabetaniafm.com.br\/novabetania87\/?p=8101"},"modified":"2025-12-05T10:05:46","modified_gmt":"2025-12-05T13:05:46","slug":"casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro","status":"publish","type":"post","link":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/","title":{"rendered":"Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro"},"content":{"rendered":"<p>A cidade de Ingazeira se prepara para celebrar o amor e a cidadania nesta sexta-feira, dia 5 de dezembro, com a realiza\u00e7\u00e3o do Casamento Comunit\u00e1rio 2025. A cerim\u00f4nia acontecer\u00e1 \u00e0s 10h da manh\u00e3, no Plen\u00e1rio da C\u00e2mara de Vereadores, e ser\u00e1 conduzida pelo Juiz da Comarca de Direito de Tuparetama, Dr. Carlos Rossi.<\/p>\n<p>&nbsp;<\/p>\n<p>A iniciativa \u00e9 uma parceria do Tribunal de Justi\u00e7a de Pernambuco (TJPE) com a Casa de Justi\u00e7a e Cidadania e a Prefeitura de Ingazeira, atrav\u00e9s do prefeito Luciano Torres, que destaca a import\u00e2ncia de a\u00e7\u00f5es como essa para o fortalecimento dos la\u00e7os familiares e sociais.<\/p>\n<p>O Casamento Comunit\u00e1rio \u00e9 uma oportunidade para casais oficializarem sua uni\u00e3o de forma gratuita, em um momento marcado por emo\u00e7\u00e3o, dignidade e inclus\u00e3o.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A cidade de Ingazeira se prepara para celebrar o amor e a cidadania nesta sexta-feira, dia 5 de dezembro, com a realiza\u00e7\u00e3o do Casamento Comunit\u00e1rio 2025. A cerim\u00f4nia acontecer\u00e1 \u00e0s 10h da manh\u00e3, no Plen\u00e1rio&#8230;<\/p>\n","protected":false},"author":4,"featured_media":8102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-8101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro - Nova Bet\u00e2nia FM 87,9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro - Nova Bet\u00e2nia FM 87,9\" \/>\n<meta property=\"og:description\" content=\"A cidade de Ingazeira se prepara para celebrar o amor e a cidadania nesta sexta-feira, dia 5 de dezembro, com a realiza\u00e7\u00e3o do Casamento Comunit\u00e1rio 2025. A cerim\u00f4nia acontecer\u00e1 \u00e0s 10h da manh\u00e3, no Plen\u00e1rio...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/\" \/>\n<meta property=\"og:site_name\" content=\"Nova Bet\u00e2nia FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-05T13:05:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nova Bet\u00e2nia FM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nova Bet\u00e2nia FM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/\"},\"author\":{\"name\":\"Nova Bet\u00e2nia FM\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555\"},\"headline\":\"Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro\",\"datePublished\":\"2025-12-05T13:05:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/\"},\"wordCount\":144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/\",\"name\":\"Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro - Nova Bet\u00e2nia FM 87,9\",\"isPartOf\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg\",\"datePublished\":\"2025-12-05T13:05:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#primaryimage\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg\",\"contentUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg\",\"width\":400,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#website\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\",\"name\":\"Nova Bet\u00e2nia FM 87,9\",\"description\":\"Ligada em voc\u00ea!\",\"publisher\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\",\"name\":\"Nova Bet\u00e2nia FM 87,9\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png\",\"contentUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png\",\"width\":211,\"height\":144,\"caption\":\"Nova Bet\u00e2nia FM 87,9\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555\",\"name\":\"Nova Bet\u00e2nia FM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"Nova Bet\u00e2nia FM\"},\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/author\/novabetaniafm879\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro - Nova Bet\u00e2nia FM 87,9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/","og_locale":"pt_BR","og_type":"article","og_title":"Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro - Nova Bet\u00e2nia FM 87,9","og_description":"A cidade de Ingazeira se prepara para celebrar o amor e a cidadania nesta sexta-feira, dia 5 de dezembro, com a realiza\u00e7\u00e3o do Casamento Comunit\u00e1rio 2025. A cerim\u00f4nia acontecer\u00e1 \u00e0s 10h da manh\u00e3, no Plen\u00e1rio...","og_url":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/","og_site_name":"Nova Bet\u00e2nia FM 87,9","article_published_time":"2025-12-05T13:05:46+00:00","og_image":[{"width":400,"height":225,"url":"http:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg","type":"image\/jpeg"}],"author":"Nova Bet\u00e2nia FM","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nova Bet\u00e2nia FM","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#article","isPartOf":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/"},"author":{"name":"Nova Bet\u00e2nia FM","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555"},"headline":"Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro","datePublished":"2025-12-05T13:05:46+00:00","mainEntityOfPage":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/"},"wordCount":144,"commentCount":0,"publisher":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#primaryimage"},"thumbnailUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/","name":"Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro - Nova Bet\u00e2nia FM 87,9","isPartOf":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#primaryimage"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#primaryimage"},"thumbnailUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg","datePublished":"2025-12-05T13:05:46+00:00","breadcrumb":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#primaryimage","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg","contentUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg","width":400,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/12\/05\/casamento-comunitario-em-ingazeira-acontece-nesta-sexta-feira-dia-5-de-dezembro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/novabetaniafm.com.br\/novabetania87\/"},{"@type":"ListItem","position":2,"name":"Casamento Comunit\u00e1rio em Ingazeira acontece nesta sexta-feira, dia 5 de dezembro"}]},{"@type":"WebSite","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#website","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/","name":"Nova Bet\u00e2nia FM 87,9","description":"Ligada em voc\u00ea!","publisher":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novabetaniafm.com.br\/novabetania87\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization","name":"Nova Bet\u00e2nia FM 87,9","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png","width":211,"height":144,"caption":"Nova Bet\u00e2nia FM 87,9"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555","name":"Nova Bet\u00e2nia FM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"Nova Bet\u00e2nia FM"},"url":"https:\/\/novabetaniafm.com.br\/novabetania87\/author\/novabetaniafm879\/"}]}},"jetpack_featured_media_url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2025\/12\/cf045438-5277-45fc-b104-2dc0464108a5.jpeg","_links":{"self":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/8101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/comments?post=8101"}],"version-history":[{"count":1,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/8101\/revisions"}],"predecessor-version":[{"id":8103,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/8101\/revisions\/8103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/media\/8102"}],"wp:attachment":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/media?parent=8101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/categories?post=8101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/tags?post=8101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}