{"id":7850,"date":"2025-11-13T06:54:04","date_gmt":"2025-11-13T09:54:04","guid":{"rendered":"https:\/\/novabetaniafm.com.br\/novabetania87\/?p=7850"},"modified":"2025-11-13T06:54:32","modified_gmt":"2025-11-13T09:54:32","slug":"varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac","status":"publish","type":"post","link":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/","title":{"rendered":"V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac"},"content":{"rendered":"<p>O Agreste e Sert\u00e3o de Pernambuco t\u00eam enfrentado muito calor e baixa umidade do ar nos \u00faltimos dias. O Instituto Nacional de Meteorologia (Inmet) e a Ag\u00eancia Pernambucana de \u00c1guas e Clima (Apac) publicaram alertas para a popula\u00e7\u00e3o destas regi\u00f5es.<\/p>\n<p>No Agreste chegou a ser registrada a temperatura de 34\u00ba durante o dia, chegando a superar os 36\u00ba, no Sert\u00e3o. Ao calor excessivo, junta-se a baixa umidade, deixando o clima ainda mais seco.<\/p>\n<p>A Apac publicou, na \u00faltima sexta-feira (7), com validade at\u00e9 o dia 14, alerta para as regi\u00f5es do Agreste, Sert\u00e3o do Paje\u00fa e do S\u00e3o Francisco, com a umidade relativa do ar ficando abaixo dos 20%.<\/p>\n<p>Nesta segunda (10), o Inmet atualizou o quadro de baixa umidade do ar confirmando a previs\u00e3o da Apac para as \u00e1reas atingidas, incluindo 58 munic\u00edpios do estado na categoria \u201cPerigo\u201d (entre 20% e 12%).<\/p>\n<p>Nestas condi\u00e7\u00f5es, aumentam os riscos de inc\u00eandio e problemas de sa\u00fade, como ressecamento da pela, desconforto nos olhos, nariz e boca.<\/p>\n<p>Apac e Inmet recomendam aos moradores destas regi\u00f5es, principalmente, o consumo de bastante \u00e1gua e evitar a realiza\u00e7\u00e3o de exerc\u00edcios f\u00edsicos entre as 10h e 17h, al\u00e9m do uso de hidratante, recomendando a umidifica\u00e7\u00e3o dos ambientes da casa.<\/p>\n<p>Confira os 58 munic\u00edpios que est\u00e3o na categoria \u201cPerigo\u201d do Inmet:<\/p>\n<p><strong>Afogados da Ingazeira<\/strong><br \/>\nAraripina<br \/>\nArcoverde<br \/>\nBel\u00e9m do S\u00e3o Francisco<br \/>\n<strong>Bet\u00e2nia<\/strong><br \/>\nBodoc\u00f3<br \/>\n<strong>Brejinho<\/strong><br \/>\nBu\u00edque<br \/>\nCabrob\u00f3<br \/>\n<strong>Calumbi<\/strong><br \/>\n<strong>Carna\u00edba<\/strong><br \/>\n<strong>Carnaubeira da Penha<\/strong><br \/>\nCedro<br \/>\n<strong>Cust\u00f3dia<\/strong><br \/>\nDormentes<br \/>\nExu<br \/>\n<strong>Flores<\/strong><br \/>\nFloresta<br \/>\nGranito<br \/>\nIbimirim<br \/>\n<strong>Iguaracy<\/strong><br \/>\nInaj\u00e1<br \/>\n<strong>Ingazeira<\/strong><br \/>\nIpubi<br \/>\nItacuruba<br \/>\nIta\u00edba<br \/>\n<strong>Itapetim<\/strong><br \/>\nJatob\u00e1<br \/>\nLagoa Grande<br \/>\nManari<br \/>\n<strong>Mirandiba<\/strong><br \/>\nMoreil\u00e2ndia<br \/>\nOroc\u00f3<br \/>\nOuricuri<br \/>\nParnamirim<br \/>\nPetrol\u00e2ndia<br \/>\nPetrolina<br \/>\n<strong>Quixaba<\/strong><br \/>\nSalgueiro<br \/>\nSanta Cruz<br \/>\n<strong>Santa Cruz da Baixa Verde<\/strong><br \/>\nSanta Filomena<br \/>\nSanta Maria da Boa Vista<br \/>\n<strong>Santa Terezinha<\/strong><br \/>\n<strong>S\u00e3o Jos\u00e9 do Belmonte<\/strong><br \/>\n<strong>S\u00e3o Jos\u00e9 do Egito<\/strong><br \/>\n<strong>Serra Talhada<\/strong><br \/>\nSerrita<br \/>\n<strong>Sert\u00e2nia<\/strong><br \/>\n<strong>Solid\u00e3o<\/strong><br \/>\n<strong>Tabira<\/strong><br \/>\nTacaratu<br \/>\nTerra Nova<br \/>\nTrindade<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>O Agreste e Sert\u00e3o de Pernambuco t\u00eam enfrentado muito calor e baixa umidade do ar nos \u00faltimos dias. O Instituto Nacional de Meteorologia (Inmet) e a Ag\u00eancia Pernambucana de \u00c1guas e Clima (Apac) publicaram alertas&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac - Nova Bet\u00e2nia FM 87,9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac - Nova Bet\u00e2nia FM 87,9\" \/>\n<meta property=\"og:description\" content=\"O Agreste e Sert\u00e3o de Pernambuco t\u00eam enfrentado muito calor e baixa umidade do ar nos \u00faltimos dias. O Instituto Nacional de Meteorologia (Inmet) e a Ag\u00eancia Pernambucana de \u00c1guas e Clima (Apac) publicaram alertas...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/\" \/>\n<meta property=\"og:site_name\" content=\"Nova Bet\u00e2nia FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-13T09:54:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T09:54:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nova Bet\u00e2nia FM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nova Bet\u00e2nia FM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/\"},\"author\":{\"name\":\"Nova Bet\u00e2nia FM\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555\"},\"headline\":\"V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac\",\"datePublished\":\"2025-11-13T09:54:04+00:00\",\"dateModified\":\"2025-11-13T09:54:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/\"},\"wordCount\":338,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/\",\"name\":\"V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac - Nova Bet\u00e2nia FM 87,9\",\"isPartOf\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg\",\"datePublished\":\"2025-11-13T09:54:04+00:00\",\"dateModified\":\"2025-11-13T09:54:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#primaryimage\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg\",\"contentUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#website\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\",\"name\":\"Nova Bet\u00e2nia FM 87,9\",\"description\":\"Ligada em voc\u00ea!\",\"publisher\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\",\"name\":\"Nova Bet\u00e2nia FM 87,9\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png\",\"contentUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png\",\"width\":211,\"height\":144,\"caption\":\"Nova Bet\u00e2nia FM 87,9\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555\",\"name\":\"Nova Bet\u00e2nia FM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"Nova Bet\u00e2nia FM\"},\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/author\/novabetaniafm879\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac - Nova Bet\u00e2nia FM 87,9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/","og_locale":"pt_BR","og_type":"article","og_title":"V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac - Nova Bet\u00e2nia FM 87,9","og_description":"O Agreste e Sert\u00e3o de Pernambuco t\u00eam enfrentado muito calor e baixa umidade do ar nos \u00faltimos dias. O Instituto Nacional de Meteorologia (Inmet) e a Ag\u00eancia Pernambucana de \u00c1guas e Clima (Apac) publicaram alertas...","og_url":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/","og_site_name":"Nova Bet\u00e2nia FM 87,9","article_published_time":"2025-11-13T09:54:04+00:00","article_modified_time":"2025-11-13T09:54:32+00:00","og_image":[{"width":1280,"height":853,"url":"http:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg","type":"image\/jpeg"}],"author":"Nova Bet\u00e2nia FM","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nova Bet\u00e2nia FM","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#article","isPartOf":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/"},"author":{"name":"Nova Bet\u00e2nia FM","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555"},"headline":"V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac","datePublished":"2025-11-13T09:54:04+00:00","dateModified":"2025-11-13T09:54:32+00:00","mainEntityOfPage":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/"},"wordCount":338,"commentCount":0,"publisher":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#primaryimage"},"thumbnailUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/","name":"V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac - Nova Bet\u00e2nia FM 87,9","isPartOf":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#primaryimage"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#primaryimage"},"thumbnailUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg","datePublished":"2025-11-13T09:54:04+00:00","dateModified":"2025-11-13T09:54:32+00:00","breadcrumb":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#primaryimage","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg","contentUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2025\/11\/13\/varias-cidades-do-sertao-de-pernambuco-sofrem-com-calor-excessivo-e-baixa-umidade-apontam-inmet-e-apac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/novabetaniafm.com.br\/novabetania87\/"},{"@type":"ListItem","position":2,"name":"V\u00e1rias cidades do Sert\u00e3o de Pernambuco sofrem com calor excessivo e baixa umidade, apontam Inmet e Apac"}]},{"@type":"WebSite","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#website","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/","name":"Nova Bet\u00e2nia FM 87,9","description":"Ligada em voc\u00ea!","publisher":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novabetaniafm.com.br\/novabetania87\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization","name":"Nova Bet\u00e2nia FM 87,9","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png","width":211,"height":144,"caption":"Nova Bet\u00e2nia FM 87,9"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555","name":"Nova Bet\u00e2nia FM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"Nova Bet\u00e2nia FM"},"url":"https:\/\/novabetaniafm.com.br\/novabetania87\/author\/novabetaniafm879\/"}]}},"jetpack_featured_media_url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2023\/09\/solforte.jpg","_links":{"self":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/7850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/comments?post=7850"}],"version-history":[{"count":1,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/7850\/revisions"}],"predecessor-version":[{"id":7851,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/7850\/revisions\/7851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/media\/1278"}],"wp:attachment":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/media?parent=7850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/categories?post=7850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/tags?post=7850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}