{"id":3382,"date":"2024-07-30T07:25:23","date_gmt":"2024-07-30T10:25:23","guid":{"rendered":"https:\/\/novabetaniafm.com.br\/novabetania87\/?p=3382"},"modified":"2024-07-30T07:25:24","modified_gmt":"2024-07-30T10:25:24","slug":"governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado","status":"publish","type":"post","link":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/","title":{"rendered":"Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado"},"content":{"rendered":"\n<p>Pela primeira vez em sua hist\u00f3ria, a Companhia Pernambucana de Saneamento (Compesa), que comemora 53 anos nesta segunda-feira (29), torna-se mutu\u00e1ria de um empr\u00e9stimo contratado diretamente junto a uma institui\u00e7\u00e3o financeira internacional no valor de R$ 1,1 bilh\u00e3o. Por meio de articula\u00e7\u00e3o do Governo do Estado, o empr\u00e9stimo foi oficializado com a assinatura do contrato em evento liderado pela governadora Raquel Lyra no Pal\u00e1cio do Campo das Princesas. Os investimentos ser\u00e3o destinados a obras estruturadoras de abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todas as regi\u00f5es do Estado. A opera\u00e7\u00e3o de cr\u00e9dito, firmada junto ao Banco Multilateral de Desenvolvimento (NDB \u2013 New Development Bank), o Banco dos Brics, foi conquistada em outubro do ano passado com garantias do Governo de Pernambuco e da Uni\u00e3o. Na ocasi\u00e3o, a governadora anunciou que ser\u00e1 publicado no Di\u00e1rio Oficial do Estado um cr\u00e9dito de R$ 193,9 milh\u00f5es em favor da Secretaria de Recursos H\u00eddricos e Saneamento, contrapartida do empr\u00e9stimo do NDB oriundo de recursos do Governo de Pernambuco.<\/p>\n\n\n\n<p><br>\u201cConseguimos assinar um novo financiamento da ordem de R$ 1,1 bilh\u00e3o com o Banco Multilateral de Desenvolvimento e esse financiamento vai permitir maiores investimentos em distribui\u00e7\u00e3o de \u00e1gua, em conclus\u00e3o de obras de adutoras, e garantir que a gente trabalhe tamb\u00e9m em saneamento b\u00e1sico e tratamento de esgoto. Essas obras acontecer\u00e3o em cada recanto de Pernambuco\u201d, destacou a governadora Raquel Lyra.<\/p>\n\n\n\n<p><br>O empr\u00e9stimo ir\u00e1 viabilizar obras nos pr\u00f3ximos cinco anos com a elimina\u00e7\u00e3o ou redu\u00e7\u00e3o do rod\u00edzio na distribui\u00e7\u00e3o de \u00e1gua em diversos munic\u00edpios, e tamb\u00e9m com a expans\u00e3o dos servi\u00e7os de esgotamento sanit\u00e1rio. Os recursos ser\u00e3o aplicados em obras de saneamento, em novas esta\u00e7\u00f5es de tratamento de \u00e1gua e na amplia\u00e7\u00e3o, adequa\u00e7\u00e3o e eficientiza\u00e7\u00e3o dos sistemas de abastecimento. O prazo de car\u00eancia do financiamento ser\u00e1 de cinco anos, com amortiza\u00e7\u00e3o de 180 meses.<\/p>\n\n\n\n<p><br>De acordo com o secret\u00e1rio de Recursos H\u00eddricos e Saneamento, Almir Cirilo, esse \u00e9 um importante marco a ser registrado. \u201cN\u00f3s estamos sempre caminhando no desafio da melhoria da quest\u00e3o h\u00eddrica no Estado. Esse contrato \u00e9 fruto de muito trabalho realizado por uma grande equipe da Compesa, que ajudou a montar essa proposta, agregando tecnologia, desenvolvimento e vontade de fazer\u201d, registrou o secret\u00e1rio. O presidente da Compesa, Alex Campos, disse que a interven\u00e7\u00e3o da governadora foi essencial para a contrata\u00e7\u00e3o da opera\u00e7\u00e3o de cr\u00e9dito. \u201cEste \u00e9 um divisor de \u00e1guas para a Compesa, uma a\u00e7\u00e3o que mostra a capacidade da companhia de estruturar projetos e apresentar solu\u00e7\u00f5es que alcan\u00e7am esse n\u00edvel de confiabilidade\u201d, afirmou.<\/p>\n\n\n\n<p><br>Como contratante de um financiamento internacional com expressivo volume de recursos, a Compesa fortalece sua estrat\u00e9gia frente aos desafios do Marco Legal do Saneamento. O objetivo \u00e9 acelerar o ritmo de investimentos em obras para o cumprimento das metas estabelecidas rumo \u00e0 universaliza\u00e7\u00e3o dos servi\u00e7os de saneamento. Todas as interven\u00e7\u00f5es planejadas advindas desse contrato ser\u00e3o executadas pela Compesa por meio do Programa de Eficientiza\u00e7\u00e3o e Expans\u00e3o do Saneamento de Pernambuco (PEX\/PE).\u00a0<br>A representante do NDB, Raiza Le\u00e3o, registrou que este \u201c\u00e9 o maior contrato de empr\u00e9stimo do NDB para uma empresa de saneamento no Brasil\u201d, celebrado para \u201cacabar com o rod\u00edzio de \u00e1gua e promover um futuro mais digno, justo e inclusivo para o Estado\u201d. Por sua vez, o procurador-geral adjunto da Fazenda Nacional, Luiz Henrique Alcoforado, desejou boa sorte na execu\u00e7\u00e3o. \u201cH\u00e1 simplesmente um ano e meio est\u00e1vamos negociando essa opera\u00e7\u00e3o, e agora, em tempo recorde, estamos assinando esse contrato. \u00c9 uma honra para o governo federal dar essa garantia, que fortalece a nossa parceria com Pernambuco\u201d, afirmou.<\/p>\n\n\n\n<p><br>Presente no evento, a deputada estadual Socorro Pimentel parabenizou a governadora e todos os envolvidos pela conquista. \u201cEstamos celebrando esse contrato de um bilh\u00e3o que ser\u00e1 transformado em investimentos, projetos e ajudar\u00e1 a universalizar a \u00e1gua para toda a popula\u00e7\u00e3o de Pernambuco\u201d, pontuou.<br><\/p>\n\n\n\n<p><strong>FORMA\u00c7\u00c3O DE MULHERES ENCANADORAS &#8211;<\/strong>\u00a0<\/p>\n\n\n\n<p>No evento, a governadora Raquel Lyra tamb\u00e9m oficializou a forma\u00e7\u00e3o de um grupo de 12 mulheres residentes em Olinda para atuar no mercado de trabalho, realizando atividades em servi\u00e7os de manuten\u00e7\u00e3o e instala\u00e7\u00e3o hidr\u00e1ulicas. As alunas integram a turma do Curso de Encanadora promovido pela Compesa em parceria com a Prefeitura de Olinda, por meio da Secretaria de Desenvolvimento Social e Direitos Humanos (SDSDH) e do Servi\u00e7o Nacional de Aprendizagem Industrial (Senai).<br>O Curso de Encanadora contempla mulheres de baixa renda, que agora ter\u00e3o a oportunidade de serem inseridas no mercado de trabalho. Em 2023, foram capacitadas 53 alunas nos munic\u00edpios de Recife e Jaboat\u00e3o dos Guararapes. Este ano foram disponibilizadas 75 vagas para mulheres, das quais 50 para Caruaru (que terminam o curso na segunda quinzena do m\u00eas de agosto) e 25 para Olinda. O curso \u00e9 gratuito e possui uma carga hor\u00e1ria de 160 horas de aulas te\u00f3ricas e pr\u00e1ticas.<br><\/p>\n\n\n\n<p><strong>CONCURSO EDUCATIVO &#8211;<\/strong><\/p>\n\n\n\n<p>\u00a0Na ocasi\u00e3o, tamb\u00e9m foram anunciados os ganhadores do concurso \u201cDesafio Educativo Socioambiental\u201d, realizado pela Compesa em parceria com a Secretaria de Educa\u00e7\u00e3o e Esportes (SEE), com premia\u00e7\u00e3o para professores e alunos das escolas da rede estadual de ensino. O objetivo do projeto \u00e9 incentivar e potencializar a reflex\u00e3o e a capacidade criativa de alunos e professores nas quest\u00f5es socioambientais, premiando-os por meio das produ\u00e7\u00f5es que atenderam aos crit\u00e9rios estabelecidos no concurso cultural nas categorias de Fotografia (professores), V\u00eddeo Reels Instagram (alunos do 6\u00ba ao 9\u00ba ano do Ensino Fundamental) e V\u00eddeo Reels Instagram (alunos do ensino m\u00e9dio).<\/p>\n\n\n\n<p><br>Participaram da cerim\u00f4nia o deputado estadual Romero Sales Filho e os secret\u00e1rios estaduais T\u00falio Vila\u00e7a (Casa Civil), Ism\u00eanio Bezerra (Crian\u00e7a e Juventude), C\u00edcero Moraes (Desenvolvimento Agr\u00e1rio, Agricultura, Pecu\u00e1ria e Pesca), Paulo Nery (Turismo e Lazer), Fabr\u00edcio Marques (Planejamento, Gest\u00e3o e Desenvolvimento Regional), Juliana Gouveia (em exerc\u00edcio da Mulher), e Fernando Holanda (Assessoria Especial e Rela\u00e7\u00f5es Internacionais).<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Pela primeira vez em sua hist\u00f3ria, a Companhia Pernambucana de Saneamento (Compesa), que comemora 53 anos nesta segunda-feira (29), torna-se mutu\u00e1ria de um empr\u00e9stimo contratado diretamente junto a uma institui\u00e7\u00e3o financeira internacional no valor de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":3383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-3382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pernambuco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado - Nova Bet\u00e2nia FM 87,9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado - Nova Bet\u00e2nia FM 87,9\" \/>\n<meta property=\"og:description\" content=\"Pela primeira vez em sua hist\u00f3ria, a Companhia Pernambucana de Saneamento (Compesa), que comemora 53 anos nesta segunda-feira (29), torna-se mutu\u00e1ria de um empr\u00e9stimo contratado diretamente junto a uma institui\u00e7\u00e3o financeira internacional no valor de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/\" \/>\n<meta property=\"og:site_name\" content=\"Nova Bet\u00e2nia FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-30T10:25:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T10:25:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nova Bet\u00e2nia FM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nova Bet\u00e2nia FM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/\"},\"author\":{\"name\":\"Nova Bet\u00e2nia FM\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555\"},\"headline\":\"Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado\",\"datePublished\":\"2024-07-30T10:25:23+00:00\",\"dateModified\":\"2024-07-30T10:25:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/\"},\"wordCount\":1051,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg\",\"articleSection\":[\"Pernambuco\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/\",\"name\":\"Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado - Nova Bet\u00e2nia FM 87,9\",\"isPartOf\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg\",\"datePublished\":\"2024-07-30T10:25:23+00:00\",\"dateModified\":\"2024-07-30T10:25:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#primaryimage\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg\",\"contentUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#website\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\",\"name\":\"Nova Bet\u00e2nia FM 87,9\",\"description\":\"Ligada em voc\u00ea!\",\"publisher\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\",\"name\":\"Nova Bet\u00e2nia FM 87,9\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png\",\"contentUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png\",\"width\":211,\"height\":144,\"caption\":\"Nova Bet\u00e2nia FM 87,9\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555\",\"name\":\"Nova Bet\u00e2nia FM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"Nova Bet\u00e2nia FM\"},\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/author\/novabetaniafm879\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado - Nova Bet\u00e2nia FM 87,9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/","og_locale":"pt_BR","og_type":"article","og_title":"Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado - Nova Bet\u00e2nia FM 87,9","og_description":"Pela primeira vez em sua hist\u00f3ria, a Companhia Pernambucana de Saneamento (Compesa), que comemora 53 anos nesta segunda-feira (29), torna-se mutu\u00e1ria de um empr\u00e9stimo contratado diretamente junto a uma institui\u00e7\u00e3o financeira internacional no valor de...","og_url":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/","og_site_name":"Nova Bet\u00e2nia FM 87,9","article_published_time":"2024-07-30T10:25:23+00:00","article_modified_time":"2024-07-30T10:25:24+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg","type":"image\/jpeg"}],"author":"Nova Bet\u00e2nia FM","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nova Bet\u00e2nia FM","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#article","isPartOf":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/"},"author":{"name":"Nova Bet\u00e2nia FM","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555"},"headline":"Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado","datePublished":"2024-07-30T10:25:23+00:00","dateModified":"2024-07-30T10:25:24+00:00","mainEntityOfPage":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/"},"wordCount":1051,"commentCount":0,"publisher":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg","articleSection":["Pernambuco"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/","name":"Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado - Nova Bet\u00e2nia FM 87,9","isPartOf":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#primaryimage"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg","datePublished":"2024-07-30T10:25:23+00:00","dateModified":"2024-07-30T10:25:24+00:00","breadcrumb":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#primaryimage","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg","contentUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/07\/30\/governadora-raquel-lyra-oficializa-emprestimo-bilionario-inedito-que-sera-destinado-para-ampliar-abastecimento-de-agua-e-esgotamento-sanitario-em-todo-o-estado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/novabetaniafm.com.br\/novabetania87\/"},{"@type":"ListItem","position":2,"name":"Governadora Raquel Lyra oficializa empr\u00e9stimo bilion\u00e1rio in\u00e9dito que ser\u00e1 destinado para ampliar abastecimento de \u00e1gua e esgotamento sanit\u00e1rio em todo o Estado"}]},{"@type":"WebSite","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#website","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/","name":"Nova Bet\u00e2nia FM 87,9","description":"Ligada em voc\u00ea!","publisher":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novabetaniafm.com.br\/novabetania87\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization","name":"Nova Bet\u00e2nia FM 87,9","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png","width":211,"height":144,"caption":"Nova Bet\u00e2nia FM 87,9"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555","name":"Nova Bet\u00e2nia FM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"Nova Bet\u00e2nia FM"},"url":"https:\/\/novabetaniafm.com.br\/novabetania87\/author\/novabetaniafm879\/"}]}},"jetpack_featured_media_url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/07\/Miva-Filho-Secom2-.jpeg","_links":{"self":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/3382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/comments?post=3382"}],"version-history":[{"count":1,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/3382\/revisions"}],"predecessor-version":[{"id":3384,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/3382\/revisions\/3384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/media\/3383"}],"wp:attachment":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/media?parent=3382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/categories?post=3382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/tags?post=3382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}