{"id":2480,"date":"2024-03-21T07:49:50","date_gmt":"2024-03-21T10:49:50","guid":{"rendered":"https:\/\/novabetaniafm.com.br\/novabetania87\/?p=2480"},"modified":"2024-03-21T07:49:51","modified_gmt":"2024-03-21T10:49:51","slug":"camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula","status":"publish","type":"post","link":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/","title":{"rendered":"C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula"},"content":{"rendered":"\n<p>A C\u00e2mara dos Deputados aprovou, na noite desta quarta-feira (20), em vota\u00e7\u00e3o simb\u00f3lica, o fim da sa\u00edda tempor\u00e1ria de presos, a chamada \u201csaidinha\u201d.<\/p>\n\n\n\n<p>O texto \u00e9 o mesmo que foi votado no Senado e seguir\u00e1 agora para san\u00e7\u00e3o do presidente Lula.<\/p>\n\n\n\n<p>O relator do projeto foi o deputado Guilherme Derrite (PL-SP), que se licenciou da Secretaria de Seguran\u00e7a P\u00fablica de S\u00e3o Paulo e retornou ao mandato para relatar a proposta. Ele afirmou que se Lula vetar a proposta, o presidente cometer\u00e1 um \u201cerro grotesco\u201d.<\/p>\n\n\n\n<p>A vota\u00e7\u00e3o do texto se deu entre v\u00e1rios discursos pr\u00f3 e contra a medida. O pr\u00f3prio autor do projeto, deputado Pedro Paulo (PSD-RJ), que o apresentou em 2011, fez discurso contra o que se tornou sua proposta original.<\/p>\n\n\n\n<p>\u201cO meu projeto original n\u00e3o previa a extin\u00e7\u00e3o da saidinha. Foi todo desfigurado. Estamos acabando com a possibilidade de ressocializa\u00e7\u00e3o do preso. Por que apenas 5% dos presos que sa\u00edram no final do ano n\u00e3o voltaram ou cometeram algum crime n\u00e3o se pode punir todos os outros 95%\u201d, disse Paulo.<\/p>\n\n\n\n<p>J\u00e1 Derrite afirmou que o projeto ir\u00e1 acabar com \u201ccinco feriad\u00f5es de uma semana\u201d dos detentos que hoje t\u00eam direito \u00e0 sa\u00edda tempor\u00e1ria.<\/p>\n\n\n\n<p>Para alguns deputados da esquerda contra o projeto, caso do PSol, argumentaram que o fim da saidinha ir\u00e1 gerar \u201cuma explos\u00e3o de viol\u00eancia\u201d nos pres\u00eddios.<\/p>\n\n\n\n<p>Com informa\u00e7\u00f5es do Correio Braziliense.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara dos Deputados aprovou, na noite desta quarta-feira (20), em vota\u00e7\u00e3o simb\u00f3lica, o fim da sa\u00edda tempor\u00e1ria de presos, a chamada \u201csaidinha\u201d. O texto \u00e9 o mesmo que foi votado no Senado e seguir\u00e1&#8230;<\/p>\n","protected":false},"author":4,"featured_media":794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula - Nova Bet\u00e2nia FM 87,9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula - Nova Bet\u00e2nia FM 87,9\" \/>\n<meta property=\"og:description\" content=\"A C\u00e2mara dos Deputados aprovou, na noite desta quarta-feira (20), em vota\u00e7\u00e3o simb\u00f3lica, o fim da sa\u00edda tempor\u00e1ria de presos, a chamada \u201csaidinha\u201d. O texto \u00e9 o mesmo que foi votado no Senado e seguir\u00e1...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/\" \/>\n<meta property=\"og:site_name\" content=\"Nova Bet\u00e2nia FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T10:49:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T10:49:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nova Bet\u00e2nia FM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nova Bet\u00e2nia FM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/\"},\"author\":{\"name\":\"Nova Bet\u00e2nia FM\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555\"},\"headline\":\"C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula\",\"datePublished\":\"2024-03-21T10:49:50+00:00\",\"dateModified\":\"2024-03-21T10:49:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/\"},\"wordCount\":259,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg\",\"articleSection\":[\"Brasil\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/\",\"name\":\"C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula - Nova Bet\u00e2nia FM 87,9\",\"isPartOf\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg\",\"datePublished\":\"2024-03-21T10:49:50+00:00\",\"dateModified\":\"2024-03-21T10:49:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#primaryimage\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg\",\"contentUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#website\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\",\"name\":\"Nova Bet\u00e2nia FM 87,9\",\"description\":\"Ligada em voc\u00ea!\",\"publisher\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\",\"name\":\"Nova Bet\u00e2nia FM 87,9\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png\",\"contentUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png\",\"width\":211,\"height\":144,\"caption\":\"Nova Bet\u00e2nia FM 87,9\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555\",\"name\":\"Nova Bet\u00e2nia FM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"Nova Bet\u00e2nia FM\"},\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/author\/novabetaniafm879\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula - Nova Bet\u00e2nia FM 87,9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/","og_locale":"pt_BR","og_type":"article","og_title":"C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula - Nova Bet\u00e2nia FM 87,9","og_description":"A C\u00e2mara dos Deputados aprovou, na noite desta quarta-feira (20), em vota\u00e7\u00e3o simb\u00f3lica, o fim da sa\u00edda tempor\u00e1ria de presos, a chamada \u201csaidinha\u201d. O texto \u00e9 o mesmo que foi votado no Senado e seguir\u00e1...","og_url":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/","og_site_name":"Nova Bet\u00e2nia FM 87,9","article_published_time":"2024-03-21T10:49:50+00:00","article_modified_time":"2024-03-21T10:49:51+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg","type":"image\/jpeg"}],"author":"Nova Bet\u00e2nia FM","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nova Bet\u00e2nia FM","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#article","isPartOf":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/"},"author":{"name":"Nova Bet\u00e2nia FM","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555"},"headline":"C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula","datePublished":"2024-03-21T10:49:50+00:00","dateModified":"2024-03-21T10:49:51+00:00","mainEntityOfPage":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/"},"wordCount":259,"commentCount":0,"publisher":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#primaryimage"},"thumbnailUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg","articleSection":["Brasil"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/","name":"C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula - Nova Bet\u00e2nia FM 87,9","isPartOf":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#primaryimage"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#primaryimage"},"thumbnailUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg","datePublished":"2024-03-21T10:49:50+00:00","dateModified":"2024-03-21T10:49:51+00:00","breadcrumb":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#primaryimage","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg","contentUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/03\/21\/camara-aprova-o-fim-da-saidinha-agora-depende-da-sansao-de-lula\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/novabetaniafm.com.br\/novabetania87\/"},{"@type":"ListItem","position":2,"name":"C\u00e2mara aprova o fim da \u201csaidinha\u201d agora depende da sans\u00e3o de Lula"}]},{"@type":"WebSite","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#website","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/","name":"Nova Bet\u00e2nia FM 87,9","description":"Ligada em voc\u00ea!","publisher":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novabetaniafm.com.br\/novabetania87\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization","name":"Nova Bet\u00e2nia FM 87,9","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png","width":211,"height":144,"caption":"Nova Bet\u00e2nia FM 87,9"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555","name":"Nova Bet\u00e2nia FM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"Nova Bet\u00e2nia FM"},"url":"https:\/\/novabetaniafm.com.br\/novabetania87\/author\/novabetaniafm879\/"}]}},"jetpack_featured_media_url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/12\/lulaaaa.jpg","_links":{"self":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/2480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/comments?post=2480"}],"version-history":[{"count":1,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/2480\/revisions"}],"predecessor-version":[{"id":2481,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/2480\/revisions\/2481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/media\/794"}],"wp:attachment":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/media?parent=2480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/categories?post=2480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/tags?post=2480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}