{"id":2426,"date":"2024-02-08T05:07:27","date_gmt":"2024-02-08T08:07:27","guid":{"rendered":"https:\/\/novabetaniafm.com.br\/novabetania87\/?p=2426"},"modified":"2024-02-08T05:07:30","modified_gmt":"2024-02-08T08:07:30","slug":"tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao","status":"publish","type":"post","link":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/","title":{"rendered":"TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o"},"content":{"rendered":"\n<p>O Tribunal de Justi\u00e7a de Pernambuco (TJPE) determinou, na quarta-feira (7), que o Sindicato dos Policiais Civis do Estado de Pernambuco (Sinpol) se abstenha de iniciar a paralisa\u00e7\u00e3o anunciada para esta sexta-feira (9).<\/p>\n\n\n\n<p>O tribunal deferiu o pedido de tutela de urg\u00eancia requerido pelo Estado de Pernambuco em decis\u00e3o redigida pelo desembargador relator C\u00e2ndido Saraiva.<\/p>\n\n\n\n<p>Caso a decis\u00e3o seja descumprida, o TJPE prev\u00ea a aplica\u00e7\u00e3o de multa di\u00e1ria de R$ 300.000,00 em desfavor da entidade. Ainda de acordo com a decis\u00e3o, caso o j\u00e1 tenha iniciado, deve ser \u201cimediatamente encerrado.\u201d<\/p>\n\n\n\n<p>A paralisa\u00e7\u00e3o dos policiais civis foi deliberada em assembleia gera realizada na noite dessa ter\u00e7a (6), ap\u00f3s uma passeata at\u00e9 o Pal\u00e1cio do Campo das Princesas, sede do governo estadual.<\/p>\n\n\n\n<p>Mais cedo, o Sinpol, por meio da sua assessoria jur\u00eddica, entrou com uma representa\u00e7\u00e3o no Centro Judici\u00e1rio de Solu\u00e7\u00e3o de Conflitos e Cidadania (Cejusc) do TJPE requerendo que a corte instaure uma media\u00e7\u00e3o entre a entidade sindical e o Poder Executivo.<\/p>\n\n\n\n<p>Do Di\u00e1rio de Pernambuco<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Justi\u00e7a de Pernambuco (TJPE) determinou, na quarta-feira (7), que o Sindicato dos Policiais Civis do Estado de Pernambuco (Sinpol) se abstenha de iniciar a paralisa\u00e7\u00e3o anunciada para esta sexta-feira (9). O tribunal&#8230;<\/p>\n","protected":false},"author":4,"featured_media":598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pernambuco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o - Nova Bet\u00e2nia FM 87,9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o - Nova Bet\u00e2nia FM 87,9\" \/>\n<meta property=\"og:description\" content=\"O Tribunal de Justi\u00e7a de Pernambuco (TJPE) determinou, na quarta-feira (7), que o Sindicato dos Policiais Civis do Estado de Pernambuco (Sinpol) se abstenha de iniciar a paralisa\u00e7\u00e3o anunciada para esta sexta-feira (9). O tribunal...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Nova Bet\u00e2nia FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-08T08:07:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-08T08:07:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"368\" \/>\n\t<meta property=\"og:image:height\" content=\"243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nova Bet\u00e2nia FM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nova Bet\u00e2nia FM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/\"},\"author\":{\"name\":\"Nova Bet\u00e2nia FM\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555\"},\"headline\":\"TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o\",\"datePublished\":\"2024-02-08T08:07:27+00:00\",\"dateModified\":\"2024-02-08T08:07:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/\"},\"wordCount\":190,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg\",\"articleSection\":[\"Pernambuco\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/\",\"name\":\"TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o - Nova Bet\u00e2nia FM 87,9\",\"isPartOf\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg\",\"datePublished\":\"2024-02-08T08:07:27+00:00\",\"dateModified\":\"2024-02-08T08:07:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#primaryimage\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg\",\"contentUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg\",\"width\":368,\"height\":243},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#website\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\",\"name\":\"Nova Bet\u00e2nia FM 87,9\",\"description\":\"Ligada em voc\u00ea!\",\"publisher\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization\",\"name\":\"Nova Bet\u00e2nia FM 87,9\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png\",\"contentUrl\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png\",\"width\":211,\"height\":144,\"caption\":\"Nova Bet\u00e2nia FM 87,9\"},\"image\":{\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555\",\"name\":\"Nova Bet\u00e2nia FM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g\",\"caption\":\"Nova Bet\u00e2nia FM\"},\"url\":\"https:\/\/novabetaniafm.com.br\/novabetania87\/author\/novabetaniafm879\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o - Nova Bet\u00e2nia FM 87,9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/","og_locale":"pt_BR","og_type":"article","og_title":"TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o - Nova Bet\u00e2nia FM 87,9","og_description":"O Tribunal de Justi\u00e7a de Pernambuco (TJPE) determinou, na quarta-feira (7), que o Sindicato dos Policiais Civis do Estado de Pernambuco (Sinpol) se abstenha de iniciar a paralisa\u00e7\u00e3o anunciada para esta sexta-feira (9). O tribunal...","og_url":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/","og_site_name":"Nova Bet\u00e2nia FM 87,9","article_published_time":"2024-02-08T08:07:27+00:00","article_modified_time":"2024-02-08T08:07:30+00:00","og_image":[{"width":368,"height":243,"url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg","type":"image\/jpeg"}],"author":"Nova Bet\u00e2nia FM","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nova Bet\u00e2nia FM","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#article","isPartOf":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/"},"author":{"name":"Nova Bet\u00e2nia FM","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555"},"headline":"TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o","datePublished":"2024-02-08T08:07:27+00:00","dateModified":"2024-02-08T08:07:30+00:00","mainEntityOfPage":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/"},"wordCount":190,"commentCount":0,"publisher":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#primaryimage"},"thumbnailUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg","articleSection":["Pernambuco"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/","name":"TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o - Nova Bet\u00e2nia FM 87,9","isPartOf":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#primaryimage"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#primaryimage"},"thumbnailUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg","datePublished":"2024-02-08T08:07:27+00:00","dateModified":"2024-02-08T08:07:30+00:00","breadcrumb":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#primaryimage","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg","contentUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg","width":368,"height":243},{"@type":"BreadcrumbList","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/2024\/02\/08\/tjpe-determina-que-policiais-civis-nao-iniciem-paralisacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/novabetaniafm.com.br\/novabetania87\/"},{"@type":"ListItem","position":2,"name":"TJPE determina que policiais civis n\u00e3o iniciem paralisa\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#website","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/","name":"Nova Bet\u00e2nia FM 87,9","description":"Ligada em voc\u00ea!","publisher":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novabetaniafm.com.br\/novabetania87\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#organization","name":"Nova Bet\u00e2nia FM 87,9","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/","url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2024\/05\/logo.png","width":211,"height":144,"caption":"Nova Bet\u00e2nia FM 87,9"},"image":{"@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/73fd05cbd77cd30a7bab1141b8ab8555","name":"Nova Bet\u00e2nia FM","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/novabetaniafm.com.br\/novabetania87\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0359add7ed5dc3560906d861b52c6a8cf5c1e199d3a7dd85070998f49bd4701?s=96&d=mm&r=g","caption":"Nova Bet\u00e2nia FM"},"url":"https:\/\/novabetaniafm.com.br\/novabetania87\/author\/novabetaniafm879\/"}]}},"jetpack_featured_media_url":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-content\/uploads\/2022\/04\/policia1.jpg","_links":{"self":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/2426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/comments?post=2426"}],"version-history":[{"count":1,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/2426\/revisions"}],"predecessor-version":[{"id":2427,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/posts\/2426\/revisions\/2427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/media\/598"}],"wp:attachment":[{"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/media?parent=2426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/categories?post=2426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/novabetaniafm.com.br\/novabetania87\/wp-json\/wp\/v2\/tags?post=2426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}